{"id":135743,"date":"2024-05-23T12:15:00","date_gmt":"2024-05-23T10:15:00","guid":{"rendered":"https:\/\/bizkeliza.org\/?p=135743"},"modified":"2024-05-23T10:27:49","modified_gmt":"2024-05-23T08:27:49","slug":"abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia","status":"publish","type":"post","link":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/","title":{"rendered":"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p>Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik <strong><a href=\"https:\/\/www.upsa.es\/actualidad\/jose-san-jose-prisco-nombrado-experto-para-el-sinodo-sobre-la-sinodalidad-por-el-papa-francisco\">Jose San Jose Prisco\u00a0<\/a><\/strong>Salamancako Pontifize Fakultateko Zuzenbide Kanonikoko dekanoak berbaldia eskaini dau Bego\u00f1ako Gogarte Etxean: <em><strong>&#8220;Parroko izan sinodo-seneko Eleizan&#8221;.\u00a0<\/strong><\/em><\/p><\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Eukaristiaren ostean, Bego\u00f1ako Gogarte Etxean senide bazkaria ospatuko dabe.<\/p><\/blockquote><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik Jose San Jose Prisco\u00a0Salamancako Pontifize Fakultateko Zuzenbide Kanonikoko dekanoak berbaldia eskaini dau Bego\u00f1ako Gogarte Etxean: &#8220;Parroko izan sinodo-seneko Eleizan&#8221;.\u00a0 Eukaristiaren ostean, Bego\u00f1ako Gogarte Etxean senide bazkaria ospatuko dabe.<\/p>\n","protected":false},"author":20,"featured_media":103897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[505,506,492],"tags":[691,534,593],"class_list":["post-135743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gotzaina","category-lehenengo-orrialdea","category-pastoral-ekintza","tag-abadea","tag-begona-eu","tag-zuzeneko-emonaldia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia<\/title>\n<meta name=\"description\" content=\"Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik, Jose San Jose Priscok berbaldia eskaini dau\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia\" \/>\n<meta property=\"og:description\" content=\"Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik, Jose San Jose Priscok berbaldia eskaini dau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bilboko Elizbarrutia - Di\u00f3cesis de Bilbao\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiocesisBilbao\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T10:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bizkeliza.org\/wp-content\/uploads\/09web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bkareaga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiocesisBilbao\" \/>\n<meta name=\"twitter:site\" content=\"@DiocesisBilbao\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/\"},\"author\":{\"name\":\"bkareaga\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#\\\/schema\\\/person\\\/1f27c53156256531056d48959c2f2008\"},\"headline\":\"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia\",\"datePublished\":\"2024-05-23T10:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/\"},\"wordCount\":45,\"publisher\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bizkeliza.org\\\/wp-content\\\/uploads\\\/09web.jpg\",\"keywords\":[\"Abadea\",\"Bego\u00f1a\",\"Zuzeneko emonaldia\"],\"articleSection\":[\"Gotzaina\",\"Lehenengo Orrialdea\",\"Pastoral ekintza\"],\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/\",\"url\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/\",\"name\":\"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bizkeliza.org\\\/wp-content\\\/uploads\\\/09web.jpg\",\"datePublished\":\"2024-05-23T10:15:00+00:00\",\"description\":\"Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik, Jose San Jose Priscok berbaldia eskaini dau\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bizkeliza.org\\\/wp-content\\\/uploads\\\/09web.jpg\",\"contentUrl\":\"https:\\\/\\\/bizkeliza.org\\\/wp-content\\\/uploads\\\/09web.jpg\",\"width\":1024,\"height\":674,\"caption\":\"Bas\u00edlica de Bego\u00f1a.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/noticia\\\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/\",\"name\":\"Di\u00f3cesis de Bilbao - Web oficial del Obispado\",\"description\":\"Di\u00f3cesis de Bilbao\",\"publisher\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#organization\"},\"alternateName\":\"Di\u00f3cesis de Bilbao\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#organization\",\"name\":\"Di\u00f3cesis de Bilbao - Web oficial del Obispado\",\"alternateName\":\"Di\u00f3cesis de Bilbao\",\"url\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bizkeliza.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo-nuevo_2024-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/bizkeliza.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo-nuevo_2024-1-scaled.jpg\",\"width\":2560,\"height\":1024,\"caption\":\"Di\u00f3cesis de Bilbao - Web oficial del Obispado\"},\"image\":{\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiocesisBilbao\\\/\",\"https:\\\/\\\/x.com\\\/DiocesisBilbao\",\"https:\\\/\\\/www.instagram.com\\\/obispadobilbao\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/bilbokoelizbarrutia\"],\"description\":\"Iglesia local de Bilbao perteneciente a la Iglesia Cat\u00f3lica\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bizkeliza.org\\\/eu\\\/#\\\/schema\\\/person\\\/1f27c53156256531056d48959c2f2008\",\"name\":\"bkareaga\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia","description":"Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik, Jose San Jose Priscok berbaldia eskaini dau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/","og_locale":"eu_ES","og_type":"article","og_title":"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia","og_description":"Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik, Jose San Jose Priscok berbaldia eskaini dau","og_url":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/","og_site_name":"Bilboko Elizbarrutia - Di\u00f3cesis de Bilbao","article_publisher":"https:\/\/www.facebook.com\/DiocesisBilbao\/","article_published_time":"2024-05-23T10:15:00+00:00","og_image":[{"width":1024,"height":674,"url":"https:\/\/bizkeliza.org\/wp-content\/uploads\/09web.jpg","type":"image\/jpeg"}],"author":"bkareaga","twitter_card":"summary_large_image","twitter_creator":"@DiocesisBilbao","twitter_site":"@DiocesisBilbao","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#article","isPartOf":{"@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/"},"author":{"name":"bkareaga","@id":"https:\/\/bizkeliza.org\/eu\/#\/schema\/person\/1f27c53156256531056d48959c2f2008"},"headline":"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia","datePublished":"2024-05-23T10:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/"},"wordCount":45,"publisher":{"@id":"https:\/\/bizkeliza.org\/eu\/#organization"},"image":{"@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#primaryimage"},"thumbnailUrl":"https:\/\/bizkeliza.org\/wp-content\/uploads\/09web.jpg","keywords":["Abadea","Bego\u00f1a","Zuzeneko emonaldia"],"articleSection":["Gotzaina","Lehenengo Orrialdea","Pastoral ekintza"],"inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/","url":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/","name":"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia","isPartOf":{"@id":"https:\/\/bizkeliza.org\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#primaryimage"},"image":{"@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#primaryimage"},"thumbnailUrl":"https:\/\/bizkeliza.org\/wp-content\/uploads\/09web.jpg","datePublished":"2024-05-23T10:15:00+00:00","description":"Abadegintzaren urteurrenak ospatzeko Eukaristiaren aurretik, Jose San Jose Priscok berbaldia eskaini dau","breadcrumb":{"@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#primaryimage","url":"https:\/\/bizkeliza.org\/wp-content\/uploads\/09web.jpg","contentUrl":"https:\/\/bizkeliza.org\/wp-content\/uploads\/09web.jpg","width":1024,"height":674,"caption":"Bas\u00edlica de Bego\u00f1a."},{"@type":"BreadcrumbList","@id":"https:\/\/bizkeliza.org\/eu\/noticia\/abadegintzaren-titanio-platino-diamante-eta-zidarrezko-ezteguen-zuzeneko-emonaldia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bizkeliza.org\/eu\/"},{"@type":"ListItem","position":2,"name":"Abadegintzaren Titanio, Platino, Diamante eta Zidarrezko Ezteguen zuzeneko emonaldia"}]},{"@type":"WebSite","@id":"https:\/\/bizkeliza.org\/eu\/#website","url":"https:\/\/bizkeliza.org\/eu\/","name":"Di\u00f3cesis de Bilbao - Web oficial del Obispado","description":"Di\u00f3cesis de Bilbao","publisher":{"@id":"https:\/\/bizkeliza.org\/eu\/#organization"},"alternateName":"Di\u00f3cesis de Bilbao","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bizkeliza.org\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/bizkeliza.org\/eu\/#organization","name":"Di\u00f3cesis de Bilbao - Web oficial del Obispado","alternateName":"Di\u00f3cesis de Bilbao","url":"https:\/\/bizkeliza.org\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/bizkeliza.org\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/bizkeliza.org\/wp-content\/uploads\/2022\/06\/Logo-nuevo_2024-1-scaled.jpg","contentUrl":"https:\/\/bizkeliza.org\/wp-content\/uploads\/2022\/06\/Logo-nuevo_2024-1-scaled.jpg","width":2560,"height":1024,"caption":"Di\u00f3cesis de Bilbao - Web oficial del Obispado"},"image":{"@id":"https:\/\/bizkeliza.org\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiocesisBilbao\/","https:\/\/x.com\/DiocesisBilbao","https:\/\/www.instagram.com\/obispadobilbao\/","https:\/\/www.youtube.com\/user\/bilbokoelizbarrutia"],"description":"Iglesia local de Bilbao perteneciente a la Iglesia Cat\u00f3lica"},{"@type":"Person","@id":"https:\/\/bizkeliza.org\/eu\/#\/schema\/person\/1f27c53156256531056d48959c2f2008","name":"bkareaga"}]}},"_links":{"self":[{"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/posts\/135743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/comments?post=135743"}],"version-history":[{"count":0,"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/posts\/135743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/media\/103897"}],"wp:attachment":[{"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/media?parent=135743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/categories?post=135743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bizkeliza.org\/eu\/wp-json\/wp\/v2\/tags?post=135743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}